{"id":3794,"date":"2018-05-02T12:03:25","date_gmt":"2018-05-02T15:03:25","guid":{"rendered":"http:\/\/165.227.28.131\/blog\/?p=3794"},"modified":"2018-05-02T12:03:25","modified_gmt":"2018-05-02T15:03:25","slug":"amazon-go-el-futuro-ya-esta-aqui","status":"publish","type":"post","link":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/","title":{"rendered":"Amazon Go: El futuro ya est\u00e1 aqu\u00ed"},"content":{"rendered":"<h4><a href=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Entrada.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright size-medium wp-image-3799\" src=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Entrada-300x400.jpeg\" alt=\"\" width=\"300\" height=\"400\" srcset=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Entrada-300x400.jpeg 300w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Entrada-768x1024.jpeg 768w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Entrada-200x267.jpeg 200w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Entrada-400x533.jpeg 400w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Entrada-600x800.jpeg 600w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Entrada-800x1067.jpeg 800w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Entrada-1200x1600.jpeg 1200w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Entrada.jpeg 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Viaj\u00e9 a Seattle por 26 horas. Cualquier ciudad merece que le dediquen m\u00e1s tiempo a ser descubierta, pero la raz\u00f3n del viaje era estrictamente laboral, as\u00ed que ese era el tiempo con el que contaba para todo: asistir al evento, visitar alg\u00fan lugar de inter\u00e9s y dormir antes de pegar la vuelta. Un par de d\u00edas antes de subirme al avi\u00f3n me sent\u00e9 a planificar la corta estad\u00eda y si hab\u00eda algo que no pod\u00eda quedar afuera de mi lista era vivir la experiencia <strong>Amazon Go<\/strong>.<br \/>\nAmazon, que propone una nueva manera de hacer las compras, abri\u00f3 al p\u00fablico este prototipo de tienda en enero de 2018.<\/h4>\n<p><strong><a href=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/App-Amazon-Go.jpeg\"><img decoding=\"async\" class=\"size-medium wp-image-3795 alignleft\" src=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/App-Amazon-Go-225x400.jpeg\" alt=\"\" width=\"225\" height=\"400\" srcset=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/App-Amazon-Go-225x400.jpeg 225w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/App-Amazon-Go-768x1365.jpeg 768w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/App-Amazon-Go-576x1024.jpeg 576w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/App-Amazon-Go-200x356.jpeg 200w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/App-Amazon-Go-400x711.jpeg 400w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/App-Amazon-Go-600x1067.jpeg 600w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/App-Amazon-Go-800x1422.jpeg 800w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/App-Amazon-Go-1200x2133.jpeg 1200w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/App-Amazon-Go.jpeg 1242w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>Amazon Go<\/strong> es un mercado sin l\u00ednea de cajas. No hay empleados con postnet m\u00f3vil como en un Apple Store, no hay colas y tampoco es necesario escanear cada uno de los productos antes de meterlos en la bolsa de compras.<\/p>\n<p>El local es un espacio de 170 m2 ubicado en 2131 7th Avenue -uno de los 18 edificios de propiedad de Amazon en Seattle- y los productos que se ofrecen, por el momento, son alimentos frescos, bebidas y golosinas.<\/p>\n<p>Toda la experiencia es tan simple y r\u00e1pida c\u00f3mo lo es hacerlo por internet.<br \/>\nEntr\u00e9, guard\u00e9 los productos en la bolsa y me fui. As\u00ed de f\u00e1cil.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3>Pero \u00bfc\u00f3mo funciona todo esto?<\/h3>\n<p>Antes de ingresar descargu\u00e9 la app que tiene asociada la cuenta de Amazon con los datos de mi tarjeta de cr\u00e9dito.<\/p>\n<p>En la entrada del local hay una especie de molinete con lector de c\u00f3digo QR (parecidos a los de las estaciones de tren o subte que leen la SUBE). Al apoyar mi tel\u00e9fono en el lector, Amazon recibi\u00f3 la informaci\u00f3n con los datos de facturaci\u00f3n. Si hubiera estado con mi familia o con amigos, ellos podr\u00edan haber ingresado tambi\u00e9n. Para alertar a Amazon sobre qui\u00e9n paga la cuenta en caso de ser m\u00e1s de uno los que realizan la compra, los acompa\u00f1antes deben entrar primero, sin registrarse con el celular y el \u00faltimo que ingresa y apoya el c\u00f3digo en el lector es el que paga.<br \/>\nUna vez adentro, solo resta elegir qu\u00e9 comer.<\/p>\n<div id='gallery-1' class='gallery galleryid-3794 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Estanterias.jpeg'><img decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Estanterias-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Estanterias-300x400.jpeg 300w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Estanterias-768x1024.jpeg 768w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Estanterias-200x267.jpeg 200w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Estanterias-400x533.jpeg 400w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Estanterias-600x800.jpeg 600w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Estanterias-800x1067.jpeg 800w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Estanterias-1200x1600.jpeg 1200w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Estanterias.jpeg 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Salida.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Salida-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Salida-300x400.jpeg 300w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Salida-768x1024.jpeg 768w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Salida-200x267.jpeg 200w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Salida-400x533.jpeg 400w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Salida-600x800.jpeg 600w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Salida-800x1067.jpeg 800w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Salida-1200x1600.jpeg 1200w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Salida.jpeg 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-3800\" src=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Comprobante-de-pago-225x400.jpeg\" alt=\"\" width=\"225\" height=\"400\" srcset=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Comprobante-de-pago-225x400.jpeg 225w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Comprobante-de-pago-768x1365.jpeg 768w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Comprobante-de-pago-576x1024.jpeg 576w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Comprobante-de-pago-200x356.jpeg 200w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Comprobante-de-pago-400x711.jpeg 400w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Comprobante-de-pago-600x1067.jpeg 600w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Comprobante-de-pago-800x1422.jpeg 800w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Comprobante-de-pago-1200x2133.jpeg 1200w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Comprobante-de-pago.jpeg 1242w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>Los sensores instalados en toda la tienda permiten detectar lo que metemos en la bolsa. Se utiliza adem\u00e1s reconocimiento facial y una tecnolog\u00eda similar a la que utilizan los autos sin conductor, que aprende del comportamiento de los consumidores.<br \/>\nAproximadamente un minuto despu\u00e9s de dejar el local, recib\u00ed el detalle de la compra.<\/p>\n<p>Con la posibilidad de pedir la devoluci\u00f3n en caso de que, por error, me hubieran facturado un \u00edtem no adquirido. Para eliminarlo, simplemente hay que deslizar el dedo hacia la izquierda sobre el nombre del producto. Lo que me llam\u00f3 la atenci\u00f3n es que decidir si incluir o no ese \u00edtem en la cuenta depend\u00eda absolutamente de m\u00ed. Ya estaba afuera de la tienda, as\u00ed que nadie iba a controlarme. \u00bfO si?<\/p>\n<p><a href=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Refund.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-3798\" src=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Refund-225x400.jpeg\" alt=\"\" width=\"225\" height=\"400\" srcset=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Refund-225x400.jpeg 225w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Refund-768x1365.jpeg 768w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Refund-576x1024.jpeg 576w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Refund-200x356.jpeg 200w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Refund-400x711.jpeg 400w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Refund-600x1067.jpeg 600w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Refund-800x1422.jpeg 800w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Refund-1200x2133.jpeg 1200w, https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/Refund.jpeg 1242w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>Yo no ped\u00ed la devoluci\u00f3n de nada, as\u00ed que no puedo confirmarles si existe alguna manera de controlar una vez afuera o a Amazon le importa muy poco los refunds malintencionados que pueda haber. Me inclino por esta \u00faltima opci\u00f3n.<\/p>\n<p>Ahora viene lo interesante.. ok, no hay cajeros, pero \u00bfhay empleados? s\u00ed y varios.<br \/>\nCont\u00e9 unas 8 personas entre los que estaban en la entrada orientando a los visitantes, dentro del local asistiendo a los compradores y curiosos o reponiendo productos. Tambi\u00e9n hay una cocina, as\u00ed que estimo que habr\u00e1 cocineros y hay c\u00e1maras, por lo que habr\u00e1 alguien monitoreando.<\/p>\n<p>Lo que intento explicar con esto es que, m\u00e1s all\u00e1 de mejorar la experiencia de compra, Amazon Go abre el debate sobre la eliminaci\u00f3n de puestos de trabajo aburridos y repetitivos. Esto que para algunos es un problema, lejos est\u00e1 de serlo. Est\u00e1 bien que los trabajos as\u00ed los haga una m\u00e1quina y no una persona. Las personas estamos para m\u00e1s. Aunque a algunos les cueste verlo de esta forma, este tipo de desarrollos crean tambi\u00e9n nuevas necesidades y ah\u00ed tenemos que estar las personas, capacit\u00e1ndonos para ocupar puestos innovadores que requieran otras habilidades: an\u00e1lisis de datos, de comportamiento, mantenimiento y muchos otros trabajos que no podr\u00eda nombrar porque hoy no existen.<\/p>\n<p>&nbsp;<\/p>\n<p>El futuro comenz\u00f3 hace rato. En Seattle, en Tokio o en el barrio de Pompeya, por ejemplo, donde naci\u00f3 Gino Tubaro, el argentino que crea pr\u00f3tesis 3D para ayudar a ni\u00f1os con discapacidad.<\/p>\n<p>El futuro est\u00e1 entre nosotros y viajar nos da la posibilidad de conocerlo e ir adapt\u00e1ndonos a \u00e9l. \u00a1Aprovechemos la oportunidad!<\/p>\n<p>&nbsp;<\/p>\n<p>Por\u00a0<a class=\"ProfileHeaderCard-screennameLink u-linkComplex js-nav\" href=\"https:\/\/twitter.com\/luligrot\"><span class=\"username u-dir\" dir=\"ltr\">@<b class=\"u-linkComplex-target\">luligrot<\/b><\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viaj\u00e9 a Seattle por 26 horas. Cualquier ciudad merece que le dediquen m\u00e1s tiempo a ser descubierta, pero la raz\u00f3n del viaje era estrictamente laboral, as\u00ed que ese era el tiempo con el que contaba para todo: asistir al evento, visitar alg\u00fan lugar de inter\u00e9s y dormir antes de pegar la vuelta. Un par de d\u00edas antes de subirme al avi\u00f3n me sent\u00e9 a planificar la corta estad\u00eda y si hab\u00eda algo que no pod\u00eda quedar afuera de mi lista era vivir la experiencia Amazon Go. Amazon, que propone una nueva manera de hacer las compras, abri\u00f3 al p\u00fablico este prototipo de tienda en enero de 2018. Amazon Go es un mercado sin l\u00ednea de cajas. No hay empleados con postnet m\u00f3vil como en un Apple Store, no hay colas y tampoco es necesario escanear cada uno de los productos antes de meterlos en la bolsa de compras. El local es un espacio de 170 m2 ubicado en 2131 7th Avenue -uno de los 18 edificios de propiedad de Amazon en Seattle- y los productos que se ofrecen, por el momento, son alimentos frescos, bebidas y golosinas. Toda la experiencia es tan simple y r\u00e1pida c\u00f3mo lo es hacerlo por internet. Entr\u00e9, guard\u00e9 los productos en la bolsa y me fui. As\u00ed de f\u00e1cil. &nbsp; &nbsp; Pero \u00bfc\u00f3mo funciona todo esto? Antes de ingresar descargu\u00e9 la app que tiene asociada la cuenta de Amazon con los datos de mi tarjeta de cr\u00e9dito. En la entrada del local hay una especie de molinete con lector de c\u00f3digo QR (parecidos a los de las estaciones de tren o subte que leen la SUBE). Al apoyar mi tel\u00e9fono en el lector, Amazon recibi\u00f3 la informaci\u00f3n con los datos de facturaci\u00f3n. Si hubiera estado con mi familia o con amigos, ellos podr\u00edan haber ingresado tambi\u00e9n. Para alertar a Amazon sobre qui\u00e9n paga la cuenta en caso de ser m\u00e1s de uno los que realizan la compra, los acompa\u00f1antes deben entrar primero, sin registrarse con el celular y el \u00faltimo que ingresa y apoya el c\u00f3digo en el lector es el que paga. Una vez adentro, solo resta elegir qu\u00e9 comer. Los sensores instalados en toda la tienda permiten detectar lo que metemos en la bolsa. Se utiliza adem\u00e1s reconocimiento facial y una tecnolog\u00eda similar a la que utilizan los autos sin conductor, que aprende del comportamiento de los consumidores. Aproximadamente un minuto despu\u00e9s de dejar el local, recib\u00ed el detalle de la compra. Con la posibilidad de pedir la devoluci\u00f3n en caso de que, por error, me hubieran facturado un \u00edtem no adquirido. Para eliminarlo, simplemente hay que deslizar el dedo hacia la izquierda sobre el nombre del producto. Lo que me llam\u00f3 la atenci\u00f3n es que decidir si incluir o no ese \u00edtem en la cuenta depend\u00eda absolutamente de m\u00ed. Ya estaba afuera de la tienda, as\u00ed que nadie iba a controlarme. \u00bfO si? Yo no ped\u00ed la devoluci\u00f3n de nada, as\u00ed que no puedo confirmarles si existe alguna manera de controlar una vez afuera o a Amazon le importa muy poco los refunds malintencionados que pueda haber. Me inclino por esta \u00faltima opci\u00f3n. Ahora viene lo interesante.. ok, no hay cajeros, pero \u00bfhay empleados? s\u00ed y varios. Cont\u00e9 unas 8 personas entre los que estaban en la entrada orientando a los visitantes, dentro del local asistiendo a los compradores y curiosos o reponiendo productos. Tambi\u00e9n hay una cocina, as\u00ed que estimo que habr\u00e1 cocineros y hay c\u00e1maras, por lo que habr\u00e1 alguien monitoreando. Lo que intento explicar con esto es que, m\u00e1s all\u00e1 de mejorar la experiencia de compra, Amazon Go abre el debate sobre la eliminaci\u00f3n de puestos de trabajo aburridos y repetitivos. Esto que para algunos es un problema, lejos est\u00e1 de serlo. Est\u00e1 bien que los trabajos as\u00ed los haga una m\u00e1quina y no una persona. Las personas estamos para m\u00e1s. Aunque a algunos les cueste verlo de esta forma, este tipo de desarrollos crean tambi\u00e9n nuevas necesidades y ah\u00ed tenemos que estar las personas, capacit\u00e1ndonos para ocupar puestos innovadores que requieran otras habilidades: an\u00e1lisis de datos, de comportamiento, mantenimiento y muchos otros trabajos que no podr\u00eda nombrar porque hoy no existen. &nbsp; El futuro comenz\u00f3 hace rato. En Seattle, en Tokio o en el barrio de Pompeya, por ejemplo, donde naci\u00f3 Gino Tubaro, el argentino que crea pr\u00f3tesis 3D para ayudar a ni\u00f1os con discapacidad. El futuro est\u00e1 entre nosotros y viajar nos da la posibilidad de conocerlo e ir adapt\u00e1ndonos a \u00e9l. \u00a1Aprovechemos la oportunidad! &nbsp; Por\u00a0@luligrot<\/p>\n","protected":false},"author":66,"featured_media":3801,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mo_disable_npp":"","_joinchat":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bloggeroqv"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amazon Go: El futuro ya est\u00e1 aqu\u00ed | QuizViajero<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amazon Go: El futuro ya est\u00e1 aqu\u00ed | QuizViajero\" \/>\n<meta property=\"og:description\" content=\"Viaj\u00e9 a Seattle por 26 horas. Cualquier ciudad merece que le dediquen m\u00e1s tiempo a ser descubierta, pero la raz\u00f3n del viaje era estrictamente laboral, as\u00ed que ese era el tiempo con el que contaba para todo: asistir al evento, visitar alg\u00fan lugar de inter\u00e9s y dormir antes de pegar la vuelta. Un par de d\u00edas antes de subirme al avi\u00f3n me sent\u00e9 a planificar la corta estad\u00eda y si hab\u00eda algo que no pod\u00eda quedar afuera de mi lista era vivir la experiencia Amazon Go. Amazon, que propone una nueva manera de hacer las compras, abri\u00f3 al p\u00fablico este prototipo de tienda en enero de 2018. Amazon Go es un mercado sin l\u00ednea de cajas. No hay empleados con postnet m\u00f3vil como en un Apple Store, no hay colas y tampoco es necesario escanear cada uno de los productos antes de meterlos en la bolsa de compras. El local es un espacio de 170 m2 ubicado en 2131 7th Avenue -uno de los 18 edificios de propiedad de Amazon en Seattle- y los productos que se ofrecen, por el momento, son alimentos frescos, bebidas y golosinas. Toda la experiencia es tan simple y r\u00e1pida c\u00f3mo lo es hacerlo por internet. Entr\u00e9, guard\u00e9 los productos en la bolsa y me fui. As\u00ed de f\u00e1cil. &nbsp; &nbsp; Pero \u00bfc\u00f3mo funciona todo esto? Antes de ingresar descargu\u00e9 la app que tiene asociada la cuenta de Amazon con los datos de mi tarjeta de cr\u00e9dito. En la entrada del local hay una especie de molinete con lector de c\u00f3digo QR (parecidos a los de las estaciones de tren o subte que leen la SUBE). Al apoyar mi tel\u00e9fono en el lector, Amazon recibi\u00f3 la informaci\u00f3n con los datos de facturaci\u00f3n. Si hubiera estado con mi familia o con amigos, ellos podr\u00edan haber ingresado tambi\u00e9n. Para alertar a Amazon sobre qui\u00e9n paga la cuenta en caso de ser m\u00e1s de uno los que realizan la compra, los acompa\u00f1antes deben entrar primero, sin registrarse con el celular y el \u00faltimo que ingresa y apoya el c\u00f3digo en el lector es el que paga. Una vez adentro, solo resta elegir qu\u00e9 comer. Los sensores instalados en toda la tienda permiten detectar lo que metemos en la bolsa. Se utiliza adem\u00e1s reconocimiento facial y una tecnolog\u00eda similar a la que utilizan los autos sin conductor, que aprende del comportamiento de los consumidores. Aproximadamente un minuto despu\u00e9s de dejar el local, recib\u00ed el detalle de la compra. Con la posibilidad de pedir la devoluci\u00f3n en caso de que, por error, me hubieran facturado un \u00edtem no adquirido. Para eliminarlo, simplemente hay que deslizar el dedo hacia la izquierda sobre el nombre del producto. Lo que me llam\u00f3 la atenci\u00f3n es que decidir si incluir o no ese \u00edtem en la cuenta depend\u00eda absolutamente de m\u00ed. Ya estaba afuera de la tienda, as\u00ed que nadie iba a controlarme. \u00bfO si? Yo no ped\u00ed la devoluci\u00f3n de nada, as\u00ed que no puedo confirmarles si existe alguna manera de controlar una vez afuera o a Amazon le importa muy poco los refunds malintencionados que pueda haber. Me inclino por esta \u00faltima opci\u00f3n. Ahora viene lo interesante.. ok, no hay cajeros, pero \u00bfhay empleados? s\u00ed y varios. Cont\u00e9 unas 8 personas entre los que estaban en la entrada orientando a los visitantes, dentro del local asistiendo a los compradores y curiosos o reponiendo productos. Tambi\u00e9n hay una cocina, as\u00ed que estimo que habr\u00e1 cocineros y hay c\u00e1maras, por lo que habr\u00e1 alguien monitoreando. Lo que intento explicar con esto es que, m\u00e1s all\u00e1 de mejorar la experiencia de compra, Amazon Go abre el debate sobre la eliminaci\u00f3n de puestos de trabajo aburridos y repetitivos. Esto que para algunos es un problema, lejos est\u00e1 de serlo. Est\u00e1 bien que los trabajos as\u00ed los haga una m\u00e1quina y no una persona. Las personas estamos para m\u00e1s. Aunque a algunos les cueste verlo de esta forma, este tipo de desarrollos crean tambi\u00e9n nuevas necesidades y ah\u00ed tenemos que estar las personas, capacit\u00e1ndonos para ocupar puestos innovadores que requieran otras habilidades: an\u00e1lisis de datos, de comportamiento, mantenimiento y muchos otros trabajos que no podr\u00eda nombrar porque hoy no existen. &nbsp; El futuro comenz\u00f3 hace rato. En Seattle, en Tokio o en el barrio de Pompeya, por ejemplo, donde naci\u00f3 Gino Tubaro, el argentino que crea pr\u00f3tesis 3D para ayudar a ni\u00f1os con discapacidad. El futuro est\u00e1 entre nosotros y viajar nos da la posibilidad de conocerlo e ir adapt\u00e1ndonos a \u00e9l. \u00a1Aprovechemos la oportunidad! &nbsp; Por\u00a0@luligrot\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/\" \/>\n<meta property=\"og:site_name\" content=\"QuizViajero\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quizviajero\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-02T15:03:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/bloggeroqv-amazongon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"@luligrot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quiz_viajero\" \/>\n<meta name=\"twitter:site\" content=\"@quiz_viajero\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"@luligrot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/amazon-go-el-futuro-ya-esta-aqui\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/amazon-go-el-futuro-ya-esta-aqui\\\/\"},\"author\":{\"name\":\"@luligrot\",\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/#\\\/schema\\\/person\\\/11e53b76f581ffb132771b322e9f3fab\"},\"headline\":\"Amazon Go: El futuro ya est\u00e1 aqu\u00ed\",\"datePublished\":\"2018-05-02T15:03:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/amazon-go-el-futuro-ya-esta-aqui\\\/\"},\"wordCount\":807,\"commentCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/amazon-go-el-futuro-ya-esta-aqui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/bloggeroqv-amazongon.jpg\",\"articleSection\":[\"#BloggeroQV\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/quizviajero.com\\\/blog\\\/amazon-go-el-futuro-ya-esta-aqui\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/amazon-go-el-futuro-ya-esta-aqui\\\/\",\"url\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/amazon-go-el-futuro-ya-esta-aqui\\\/\",\"name\":\"Amazon Go: El futuro ya est\u00e1 aqu\u00ed | QuizViajero\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/amazon-go-el-futuro-ya-esta-aqui\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/amazon-go-el-futuro-ya-esta-aqui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/bloggeroqv-amazongon.jpg\",\"datePublished\":\"2018-05-02T15:03:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/amazon-go-el-futuro-ya-esta-aqui\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quizviajero.com\\\/blog\\\/amazon-go-el-futuro-ya-esta-aqui\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/amazon-go-el-futuro-ya-esta-aqui\\\/#primaryimage\",\"url\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/bloggeroqv-amazongon.jpg\",\"contentUrl\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/bloggeroqv-amazongon.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/amazon-go-el-futuro-ya-esta-aqui\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#BloggeroQV\",\"item\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/bloggeroqv\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Amazon Go: El futuro ya est\u00e1 aqu\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/\",\"name\":\"QuizViajero\",\"description\":\"El primer juego sobre viajes con premios! \u2708\",\"publisher\":{\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/#organization\",\"name\":\"QuizViajero\",\"url\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/cropped-qv_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/cropped-qv_logo-1.png\",\"width\":301,\"height\":100,\"caption\":\"QuizViajero\"},\"image\":{\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/quizviajero\\\/\",\"https:\\\/\\\/x.com\\\/quiz_viajero\",\"http:\\\/\\\/instagram.com\\\/quizviajeroig\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/#\\\/schema\\\/person\\\/11e53b76f581ffb132771b322e9f3fab\",\"name\":\"@luligrot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b772931851741fb82c98c4910b86aee4a4bf3659cd19d994bb7b32626cb3bd4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b772931851741fb82c98c4910b86aee4a4bf3659cd19d994bb7b32626cb3bd4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b772931851741fb82c98c4910b86aee4a4bf3659cd19d994bb7b32626cb3bd4?s=96&d=mm&r=g\",\"caption\":\"@luligrot\"},\"url\":\"https:\\\/\\\/quizviajero.com\\\/blog\\\/author\\\/luligrot\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amazon Go: El futuro ya est\u00e1 aqu\u00ed | QuizViajero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/","og_locale":"es_ES","og_type":"article","og_title":"Amazon Go: El futuro ya est\u00e1 aqu\u00ed | QuizViajero","og_description":"Viaj\u00e9 a Seattle por 26 horas. Cualquier ciudad merece que le dediquen m\u00e1s tiempo a ser descubierta, pero la raz\u00f3n del viaje era estrictamente laboral, as\u00ed que ese era el tiempo con el que contaba para todo: asistir al evento, visitar alg\u00fan lugar de inter\u00e9s y dormir antes de pegar la vuelta. Un par de d\u00edas antes de subirme al avi\u00f3n me sent\u00e9 a planificar la corta estad\u00eda y si hab\u00eda algo que no pod\u00eda quedar afuera de mi lista era vivir la experiencia Amazon Go. Amazon, que propone una nueva manera de hacer las compras, abri\u00f3 al p\u00fablico este prototipo de tienda en enero de 2018. Amazon Go es un mercado sin l\u00ednea de cajas. No hay empleados con postnet m\u00f3vil como en un Apple Store, no hay colas y tampoco es necesario escanear cada uno de los productos antes de meterlos en la bolsa de compras. El local es un espacio de 170 m2 ubicado en 2131 7th Avenue -uno de los 18 edificios de propiedad de Amazon en Seattle- y los productos que se ofrecen, por el momento, son alimentos frescos, bebidas y golosinas. Toda la experiencia es tan simple y r\u00e1pida c\u00f3mo lo es hacerlo por internet. Entr\u00e9, guard\u00e9 los productos en la bolsa y me fui. As\u00ed de f\u00e1cil. &nbsp; &nbsp; Pero \u00bfc\u00f3mo funciona todo esto? Antes de ingresar descargu\u00e9 la app que tiene asociada la cuenta de Amazon con los datos de mi tarjeta de cr\u00e9dito. En la entrada del local hay una especie de molinete con lector de c\u00f3digo QR (parecidos a los de las estaciones de tren o subte que leen la SUBE). Al apoyar mi tel\u00e9fono en el lector, Amazon recibi\u00f3 la informaci\u00f3n con los datos de facturaci\u00f3n. Si hubiera estado con mi familia o con amigos, ellos podr\u00edan haber ingresado tambi\u00e9n. Para alertar a Amazon sobre qui\u00e9n paga la cuenta en caso de ser m\u00e1s de uno los que realizan la compra, los acompa\u00f1antes deben entrar primero, sin registrarse con el celular y el \u00faltimo que ingresa y apoya el c\u00f3digo en el lector es el que paga. Una vez adentro, solo resta elegir qu\u00e9 comer. Los sensores instalados en toda la tienda permiten detectar lo que metemos en la bolsa. Se utiliza adem\u00e1s reconocimiento facial y una tecnolog\u00eda similar a la que utilizan los autos sin conductor, que aprende del comportamiento de los consumidores. Aproximadamente un minuto despu\u00e9s de dejar el local, recib\u00ed el detalle de la compra. Con la posibilidad de pedir la devoluci\u00f3n en caso de que, por error, me hubieran facturado un \u00edtem no adquirido. Para eliminarlo, simplemente hay que deslizar el dedo hacia la izquierda sobre el nombre del producto. Lo que me llam\u00f3 la atenci\u00f3n es que decidir si incluir o no ese \u00edtem en la cuenta depend\u00eda absolutamente de m\u00ed. Ya estaba afuera de la tienda, as\u00ed que nadie iba a controlarme. \u00bfO si? Yo no ped\u00ed la devoluci\u00f3n de nada, as\u00ed que no puedo confirmarles si existe alguna manera de controlar una vez afuera o a Amazon le importa muy poco los refunds malintencionados que pueda haber. Me inclino por esta \u00faltima opci\u00f3n. Ahora viene lo interesante.. ok, no hay cajeros, pero \u00bfhay empleados? s\u00ed y varios. Cont\u00e9 unas 8 personas entre los que estaban en la entrada orientando a los visitantes, dentro del local asistiendo a los compradores y curiosos o reponiendo productos. Tambi\u00e9n hay una cocina, as\u00ed que estimo que habr\u00e1 cocineros y hay c\u00e1maras, por lo que habr\u00e1 alguien monitoreando. Lo que intento explicar con esto es que, m\u00e1s all\u00e1 de mejorar la experiencia de compra, Amazon Go abre el debate sobre la eliminaci\u00f3n de puestos de trabajo aburridos y repetitivos. Esto que para algunos es un problema, lejos est\u00e1 de serlo. Est\u00e1 bien que los trabajos as\u00ed los haga una m\u00e1quina y no una persona. Las personas estamos para m\u00e1s. Aunque a algunos les cueste verlo de esta forma, este tipo de desarrollos crean tambi\u00e9n nuevas necesidades y ah\u00ed tenemos que estar las personas, capacit\u00e1ndonos para ocupar puestos innovadores que requieran otras habilidades: an\u00e1lisis de datos, de comportamiento, mantenimiento y muchos otros trabajos que no podr\u00eda nombrar porque hoy no existen. &nbsp; El futuro comenz\u00f3 hace rato. En Seattle, en Tokio o en el barrio de Pompeya, por ejemplo, donde naci\u00f3 Gino Tubaro, el argentino que crea pr\u00f3tesis 3D para ayudar a ni\u00f1os con discapacidad. El futuro est\u00e1 entre nosotros y viajar nos da la posibilidad de conocerlo e ir adapt\u00e1ndonos a \u00e9l. \u00a1Aprovechemos la oportunidad! &nbsp; Por\u00a0@luligrot","og_url":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/","og_site_name":"QuizViajero","article_publisher":"https:\/\/www.facebook.com\/quizviajero\/","article_published_time":"2018-05-02T15:03:25+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/bloggeroqv-amazongon.jpg","type":"image\/jpeg"}],"author":"@luligrot","twitter_card":"summary_large_image","twitter_creator":"@quiz_viajero","twitter_site":"@quiz_viajero","twitter_misc":{"Escrito por":"@luligrot","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/#article","isPartOf":{"@id":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/"},"author":{"name":"@luligrot","@id":"https:\/\/quizviajero.com\/blog\/#\/schema\/person\/11e53b76f581ffb132771b322e9f3fab"},"headline":"Amazon Go: El futuro ya est\u00e1 aqu\u00ed","datePublished":"2018-05-02T15:03:25+00:00","mainEntityOfPage":{"@id":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/"},"wordCount":807,"commentCount":10,"publisher":{"@id":"https:\/\/quizviajero.com\/blog\/#organization"},"image":{"@id":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/#primaryimage"},"thumbnailUrl":"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/bloggeroqv-amazongon.jpg","articleSection":["#BloggeroQV"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/","url":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/","name":"Amazon Go: El futuro ya est\u00e1 aqu\u00ed | QuizViajero","isPartOf":{"@id":"https:\/\/quizviajero.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/#primaryimage"},"image":{"@id":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/#primaryimage"},"thumbnailUrl":"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/bloggeroqv-amazongon.jpg","datePublished":"2018-05-02T15:03:25+00:00","breadcrumb":{"@id":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/#primaryimage","url":"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/bloggeroqv-amazongon.jpg","contentUrl":"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2018\/05\/bloggeroqv-amazongon.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/quizviajero.com\/blog\/amazon-go-el-futuro-ya-esta-aqui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/quizviajero.com\/blog\/"},{"@type":"ListItem","position":2,"name":"#BloggeroQV","item":"https:\/\/quizviajero.com\/blog\/bloggeroqv\/"},{"@type":"ListItem","position":3,"name":"Amazon Go: El futuro ya est\u00e1 aqu\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/quizviajero.com\/blog\/#website","url":"https:\/\/quizviajero.com\/blog\/","name":"QuizViajero","description":"El primer juego sobre viajes con premios! \u2708","publisher":{"@id":"https:\/\/quizviajero.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quizviajero.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/quizviajero.com\/blog\/#organization","name":"QuizViajero","url":"https:\/\/quizviajero.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/quizviajero.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2016\/11\/cropped-qv_logo-1.png","contentUrl":"https:\/\/quizviajero.com\/blog\/wp-content\/uploads\/2016\/11\/cropped-qv_logo-1.png","width":301,"height":100,"caption":"QuizViajero"},"image":{"@id":"https:\/\/quizviajero.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/quizviajero\/","https:\/\/x.com\/quiz_viajero","http:\/\/instagram.com\/quizviajeroig"]},{"@type":"Person","@id":"https:\/\/quizviajero.com\/blog\/#\/schema\/person\/11e53b76f581ffb132771b322e9f3fab","name":"@luligrot","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5b772931851741fb82c98c4910b86aee4a4bf3659cd19d994bb7b32626cb3bd4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b772931851741fb82c98c4910b86aee4a4bf3659cd19d994bb7b32626cb3bd4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b772931851741fb82c98c4910b86aee4a4bf3659cd19d994bb7b32626cb3bd4?s=96&d=mm&r=g","caption":"@luligrot"},"url":"https:\/\/quizviajero.com\/blog\/author\/luligrot\/"}]}},"_links":{"self":[{"href":"https:\/\/quizviajero.com\/blog\/wp-json\/wp\/v2\/posts\/3794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quizviajero.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quizviajero.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quizviajero.com\/blog\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quizviajero.com\/blog\/wp-json\/wp\/v2\/comments?post=3794"}],"version-history":[{"count":0,"href":"https:\/\/quizviajero.com\/blog\/wp-json\/wp\/v2\/posts\/3794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quizviajero.com\/blog\/wp-json\/wp\/v2\/media\/3801"}],"wp:attachment":[{"href":"https:\/\/quizviajero.com\/blog\/wp-json\/wp\/v2\/media?parent=3794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quizviajero.com\/blog\/wp-json\/wp\/v2\/categories?post=3794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quizviajero.com\/blog\/wp-json\/wp\/v2\/tags?post=3794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}